{"id":28041,"date":"2024-07-05T06:00:41","date_gmt":"2024-07-05T04:00:41","guid":{"rendered":"https:\/\/www.sabine-seyffert.de\/blog\/?p=28041"},"modified":"2024-06-06T09:22:02","modified_gmt":"2024-06-06T07:22:02","slug":"sommer-diy-3d-ananas-mit-kindern-basteln","status":"publish","type":"post","link":"https:\/\/www.sabine-seyffert.de\/blog\/sommer-diy-3d-ananas-mit-kindern-basteln\/","title":{"rendered":"Sommer DIY: 3D Ananas mit Kindern basteln"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg05.met.vgwort.de\/na\/5a0fa56346ee4ea48d4eac1a67ad288b\" alt=\"\" width=\"1\" height=\"1\" \/>Passend zum Sommer gibt es eine fruchtig s\u00fc\u00dfe Bastelidee f\u00fcr euch. Die tolle Ananas kann man als Sommerdeko und Bild verwenden, aber ebenso gut als Einladungskarte f\u00fcr ein Sommerfest oder einen sommerlichen Kindergeburtstag. Denn die Ananas bekommt durch den gr\u00fcnen Strunk, der aus einer Klorolle gebastelt ist, einen pfiffigen 3D Effekt. Aber nun werde ich euch die detaillierte Bastelanleitung die dieses Sommer DIY verraten.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28043\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-13.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-13.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-13-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-13-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Das wird gebraucht:<\/strong><br \/>\nPappe \/ ein leerer Karton, eine Bastelschere, eine Klorolle, Pastellkreide, einen Wasserfarbkasten inklusiv Deckwei\u00df (alternativ Bastelfarbe), Pinsel \/ Borstenpinsel, eine alte Tageszeitung, Bastelkleber \/ Klebestift, eine Malunterlage und einen <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=12310\" target=\"_blank\" rel=\"noopener\">Bastelkittel<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28047\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-0.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-0.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-0-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-0-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>So wird\u2019s gemacht:<\/strong><br \/>\nDeckt den Tisch ab und zieht euch einen Malkittel an. Stell euch dann aus Wasserfarbe und Zeitung <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=13917\" target=\"_blank\" rel=\"noopener\">nachhaltiges Bastelpapier<\/a> her.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28048\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de_.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de_.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de_-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de_-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ihr ben\u00f6tigt f\u00fcr die Frucht die Farbe Gelb und eine weitere Farbe f\u00fcr den Hintergrund.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28049\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-9.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-9.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-9-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-9-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Lasst euch dann von einem Erwachsenen helfen und mit Hilfe einer scharfen Schere oder einem Bastelmesser ein etwa Din A5 gro\u00dfes St\u00fcck Pappe aus einem Karton schneiden.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28050\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-8.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-8.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-8-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-8-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Dann bemalt die Klopapierrolle von au\u00dfen mit gr\u00fcner Wasserfarbe.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28051\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-7.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-7.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-7-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-7-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Schneidet euch aus dem selbst gemachten Bastelpapier ein Rechteck, das etwa 1-2 cm kleiner als die Pappe ist und klebt dieses auf.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28052\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-6.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-6.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-6-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-6-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Rei\u00dft etwas von dem gelb bemalten Zeitungspapier in kleinere St\u00fccke und zeichnet euch ggf. mit einem Bleistift die Form der Ananas vor. Danach klebt ihr die gelben Schnipsel dich nebeneinander, bis ihr eine sch\u00f6ne Ananas habt.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28053\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-5.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-5.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-5-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-5-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Mit Hilfe von brauner Pastellkreide kann man in gleichm\u00e4\u00dfigen Abst\u00e4nden Linien auf die geklebte Ananas zeichnen, so dass diese das f\u00fcr die Schale typische Muster bekommt.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28054\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-4.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-4.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-4-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-4-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Schneidet die gr\u00fcn bemalte Klorolle in unterschiedlich breite Streifen und schnippelt diese nach oben hin spitz zu. Klebt diese Bl\u00e4tter oben mittig an die Ananas.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28055\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-2.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-2.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-2-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-2-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Ein kleiner Tipp:<\/strong><br \/>\nFalls ihr eine Hei\u00dfklebepistole zum Basteln habt, lassen sich die gr\u00fcnen Klorollen Streifen damit blitzschnell und gut befestigen, ohne das die Bl\u00e4tter verrutschen oder abfallen.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28056\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-1.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-1.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-1-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Wenn ihr Ananas als Motiv auch so gerne m\u00f6gt, dann schaut gerne mal durch folgende Bastelideen zu dieser Frucht:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28046\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-12.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-12.jpg 800w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-12-300x225.jpg 300w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-12-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">* <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=14739\" target=\"_blank\" rel=\"noopener\">Fruchtige Geschenkverpackung mit Ananas Lolli<\/a><br \/>\n* <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=20732\" target=\"_blank\" rel=\"noopener\">Lustige Caketopper mit Ananas<\/a><br \/>\n* <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=17017\" target=\"_blank\" rel=\"noopener\">Nachhaltige \u00dcberraschungs-Ananas<\/a><br \/>\n* <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=14801\" target=\"_blank\" rel=\"noopener\">Sommerliche Ananas Girlande<\/a><br \/>\n* <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=16972\" target=\"_blank\" rel=\"noopener\">DIY Windlicht: Eine leuchtende Ananas<\/a><br \/>\n* <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?p=23047\" target=\"_blank\" rel=\"noopener\">Upcycling Ananas aus Walnuss Schale<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-15.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28045\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-15.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-15.jpg 600w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-15-225x300.jpg 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Weitere Ideen zur Sommerzeit findet ihr \u00fcbrigens in <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?cat=24\" target=\"_blank\" rel=\"noopener\">dieser Blog Kategorie<\/a>, alle DIY zum Thema Kindergeburtstag gibt es in <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?cat=21\" target=\"_blank\" rel=\"noopener\">dieser Rubrik<\/a>, kreative Bastelideen f\u00fcr Kinder werden in <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?cat=32\" target=\"_blank\" rel=\"noopener\">diesem Blog Ordner<\/a> gesammelt und andere kreative Sachen auch an meinen <a href=\"https:\/\/www.pinterest.de\/diysabineseyffert\/\" target=\"_blank\" rel=\"noopener\">Pinterest Pinnw\u00e4nden<\/a>.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-16.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-28044\" src=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-16.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-16.jpg 600w, https:\/\/www.sabine-seyffert.de\/blog\/wp-content\/uploads\/2024\/06\/Ananas-Schnispsel-Klorolle-Sabine-Seyffert.de-16-225x300.jpg 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.sabine-seyffert.de\/blog\/?page_id=32#urheberrecht\">urheberrechtlich gesch\u00fctzt<\/a>, \u00a9 Sabine Seyffert<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passend zum Sommer gibt es eine fruchtig s\u00fc\u00dfe Bastelidee f\u00fcr euch. Die tolle Ananas kann man als Sommerdeko und Bild verwenden, aber ebenso gut als Einladungskarte f\u00fcr ein Sommerfest oder einen sommerlichen Kindergeburtstag. Denn die Ananas bekommt durch den gr\u00fcnen Strunk, der aus einer Klorolle gebastelt ist, einen pfiffigen 3D Effekt. Aber nun werde ich&#8230; <a href=\"https:\/\/www.sabine-seyffert.de\/blog\/sommer-diy-3d-ananas-mit-kindern-basteln\/\" class=\"more-link\">Read more: Sommer DIY: 3D Ananas mit Kindern basteln<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_metis_text_type":"standard","_metis_text_length":2717,"_post_count":0,"footnotes":""},"categories":[32,51,24,47],"tags":[],"class_list":["post-28041","post","type-post","status-publish","format-standard","hentry","category-kreatives-fur-kleine-kinderhande","category-postkarten-grusskarten","category-sommer","category-upcyceltes"],"_links":{"self":[{"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/posts\/28041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/comments?post=28041"}],"version-history":[{"count":3,"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/posts\/28041\/revisions"}],"predecessor-version":[{"id":28058,"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/posts\/28041\/revisions\/28058"}],"wp:attachment":[{"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/media?parent=28041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/categories?post=28041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabine-seyffert.de\/blog\/wp-json\/wp\/v2\/tags?post=28041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}